{"id":665,"count":0,"description":"","link":"https:\/\/95glassbottles.com\/fr\/c\/bouteilles-dalcool-de-100-ml\/","name":"Bouteilles d&#039;alcool de 100 ml","slug":"bouteilles-dalcool-de-100-ml","taxonomy":"product_cat","parent":0,"meta":[],"menu_order":0,"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Bouteilles d&#039;alcool de 100 ml Collections | 95Glass<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/95glassbottles.com\/fr\/c\/bouteilles-dalcool-de-100-ml\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bouteilles d&#039;alcool de 100 ml Collections | 95Glass\" \/>\n<meta property=\"og:url\" content=\"https:\/\/95glassbottles.com\/fr\/c\/bouteilles-dalcool-de-100-ml\/\" \/>\n<meta property=\"og:site_name\" content=\"95Glass\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/95glassbottles.com\\\/fr\\\/c\\\/bouteilles-dalcool-de-100-ml\\\/\",\"url\":\"https:\\\/\\\/95glassbottles.com\\\/fr\\\/c\\\/bouteilles-dalcool-de-100-ml\\\/\",\"name\":\"Bouteilles d&#039;alcool de 100 ml Collections | 95Glass\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/95glassbottles.com\\\/fr\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/95glassbottles.com\\\/fr\\\/c\\\/bouteilles-dalcool-de-100-ml\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/95glassbottles.com\\\/fr\\\/c\\\/bouteilles-dalcool-de-100-ml\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/95glassbottles.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bouteilles d&#039;alcool de 100 ml\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/95glassbottles.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/95glassbottles.com\\\/fr\\\/\",\"name\":\"95GlassBottles\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/95glassbottles.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/95glassbottles.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/95glassbottles.com\\\/fr\\\/#organization\",\"name\":\"Shandong Ninety Five Glass Co,.Ltd\",\"url\":\"https:\\\/\\\/95glassbottles.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/95glassbottles.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/95glassbottles.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/1-3.webp\",\"contentUrl\":\"https:\\\/\\\/95glassbottles.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/1-3.webp\",\"width\":350,\"height\":100,\"caption\":\"Shandong Ninety Five Glass Co,.Ltd\"},\"image\":{\"@id\":\"https:\\\/\\\/95glassbottles.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/95Glass\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bouteilles d&#039;alcool de 100 ml Collections | 95Glass","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/95glassbottles.com\/fr\/c\/bouteilles-dalcool-de-100-ml\/","og_locale":"fr_FR","og_type":"article","og_title":"Bouteilles d&#039;alcool de 100 ml Collections | 95Glass","og_url":"https:\/\/95glassbottles.com\/fr\/c\/bouteilles-dalcool-de-100-ml\/","og_site_name":"95Glass","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/95glassbottles.com\/fr\/c\/bouteilles-dalcool-de-100-ml\/","url":"https:\/\/95glassbottles.com\/fr\/c\/bouteilles-dalcool-de-100-ml\/","name":"Bouteilles d&#039;alcool de 100 ml Collections | 95Glass","isPartOf":{"@id":"https:\/\/95glassbottles.com\/fr\/#website"},"breadcrumb":{"@id":"https:\/\/95glassbottles.com\/fr\/c\/bouteilles-dalcool-de-100-ml\/#breadcrumb"},"inLanguage":"fr-FR"},{"@type":"BreadcrumbList","@id":"https:\/\/95glassbottles.com\/fr\/c\/bouteilles-dalcool-de-100-ml\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/95glassbottles.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Bouteilles d&#039;alcool de 100 ml"}]},{"@type":"WebSite","@id":"https:\/\/95glassbottles.com\/fr\/#website","url":"https:\/\/95glassbottles.com\/fr\/","name":"95GlassBottles","description":"","publisher":{"@id":"https:\/\/95glassbottles.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/95glassbottles.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/95glassbottles.com\/fr\/#organization","name":"Shandong Ninety Five Glass Co,.Ltd","url":"https:\/\/95glassbottles.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/95glassbottles.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/95glassbottles.com\/wp-content\/uploads\/2025\/04\/1-3.webp","contentUrl":"https:\/\/95glassbottles.com\/wp-content\/uploads\/2025\/04\/1-3.webp","width":350,"height":100,"caption":"Shandong Ninety Five Glass Co,.Ltd"},"image":{"@id":"https:\/\/95glassbottles.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/95Glass"]}]}},"_links":{"self":[{"href":"https:\/\/95glassbottles.com\/fr\/wp-json\/wp\/v2\/product_cat\/665","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/95glassbottles.com\/fr\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/95glassbottles.com\/fr\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/95glassbottles.com\/fr\/wp-json\/wp\/v2\/product?product_cat=665"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}